{"id":679,"date":"2018-02-20T22:37:17","date_gmt":"2018-02-20T21:37:17","guid":{"rendered":"http:\/\/architectedevosreves.com\/?p=679"},"modified":"2025-11-07T11:38:25","modified_gmt":"2025-11-07T10:38:25","slug":"lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie","status":"publish","type":"post","link":"https:\/\/architectedevosreves.com\/es\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/","title":{"rendered":"L&rsquo;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie"},"content":{"rendered":"<p style=\"text-align: center;\">L&rsquo;alchimie de la vie<\/p>\n<p style=\"text-align: center;\">Petit mode d&#8217;emploi pour transformer les \u00e9preuves en cadeaux\u00a0!<\/p>\n<p style=\"text-align: center;\">T\u00e9moignage de Patricia Lagier<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.patricialagier.com\/\">\u00a0site<\/a>\u00a0internet<\/p>\n<p style=\"text-align: center;\">Th\u00e9rapeute ma\u00efeutique<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27\" src=\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/11\/arbre-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/11\/arbre-300x169.jpg 300w, https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/11\/arbre-768x433.jpg 768w, https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/11\/arbre.jpg 849w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><em>\u00a0Peinture de Cameron Gray<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00ab\u00a0Dans la beaut\u00e9 j&rsquo;avance. Pr\u00e9c\u00e9d\u00e9 de la beaut\u00e9 j&rsquo;avance. Aur\u00e9ole par la beaut\u00e9 j&rsquo;avance.\u00a0\u00bb <\/em><\/p>\n<p><em>Extrait du \u00ab\u00a0 Chant de la nuit\u00a0\u00bb Po\u00e8me navajo<\/em><\/p>\n<p><em>\u00ab\u00a0Il est important d\u2019avoir des r\u00eaves assez grands,<\/em><\/p>\n<p><em>\u00a0pour ne pas les perdre de vue, lorsqu\u2019on les poursuit\u00a0.<\/em><\/p>\n<p><em>Pas une carte au monde n&rsquo;est digne d&rsquo;un regard si le pays de l&rsquo;utopie n&rsquo;y figure pas.\u00a0\u00bb<\/em><\/p>\n<p><em>\u00a0<\/em><em>Oscar Wilde<\/em><\/p>\n<p><strong>Avertissement<\/strong><\/p>\n<p>Je ne suis pas une scientifique mais une chercheuse, en dehors de toute \u00e9cole ou dogmatisme.<\/p>\n<p>Toutes mes croyances ne demandent qu\u2019\u00e0 \u00eatre v\u00e9rifi\u00e9es par votre esprit critique, votre exp\u00e9rience et vos ressentis.<\/p>\n<p>Ne me croyez pas sur parole. \u00c9coutez et sentez ce qui r\u00e9sonne juste en vous. Allez v\u00e9rifier tout ce qui ne vous semble pas coh\u00e9rent.<\/p>\n<p>\u00c9coutez votre\u00a0\u00ab\u00a0bon sens\u00a0\u00bb et prenez comme rep\u00e8re la nature.<\/p>\n<p>Par exemple demandez-vous comment pousse une fleur\u00a0: \u00e0 partir des p\u00e9tales ou \u00e0 partir de la graine\u00a0?<\/p>\n<p><strong>Prologue<\/strong><\/p>\n<p>Nous nous demandons tous \u00e0 quoi sert la vie\u00a0?<\/p>\n<p>Pourquoi sommes-nous sur terre\u00a0?<\/p>\n<p>Du\u00a0 moins, je crois savoir que c\u2019est une question que se posent beaucoup de gens et ce d\u00e8s l\u2019enfance.<\/p>\n<p>Pour ma part c\u2019est une question fondamentale que je me suis toujours pos\u00e9e. Enfant je cherchais \u00e0 tout expliquer, ce qui n&rsquo;en finissait pas d&rsquo;agacer mes parents.<\/p>\n<p>Je renversais de l\u2019eau \u00e0 table et je me lan\u00e7ais dans une grande th\u00e9orie!<\/p>\n<p>La moindre chose m\u00e9ritait une explication tout avait un sens\u00a0!<\/p>\n<p>Par la suite ce besoin de sens n\u2019a cess\u00e9 de me hanter, toujours vouloir comprendre le sens de chaque \u00e9v\u00e9nement.<\/p>\n<p>Le pourquoi des choses, \u00e0 quoi cela sert-il de vivre,\u00a0et dans quel but\u00a0?<\/p>\n<p>L&rsquo;id\u00e9e de vivre pour vivre parce que de toute fa\u00e7on on est l\u00e0 et qu\u2019on doit faire avec, ne me satisfaisait pas.<\/p>\n<p><strong>\u00a0A travers ce petit ouvrage je vais tenter de vous exposer succinctement mes d\u00e9couvertes personnelles. Beaucoup de mes r\u00e9flexions et de mes intuitions m&rsquo;ont \u00e9t\u00e9 confirm\u00e9es beaucoup plus tard en \u00e9tudiant la physique quantique et bien s\u00fbr par\u00a0 mes exp\u00e9riences. Ce qui me permet maintenant de me faire plus confiance .<\/strong><\/p>\n<p><strong>Beaucoup de personnes offrent gratuitement leurs \u00e9crits sur la toile. Moi pour l&rsquo;instant je ne peux pas me le permettre, ces 60 pages \u00e9crites en 2011 pour r\u00e9pondre \u00e0 des questions m&rsquo;ont demand\u00e9 beaucoup de temps et de corrections . Je n&rsquo;ai pour l&rsquo;instant pas de sponsor, ni de revenus r\u00e9guliers alors, je l&rsquo;\u00e9change contre 8\u20ac.<\/strong><\/p>\n<p><strong>C&rsquo;est une fa\u00e7on pour vous de me soutenir dans mes recherches sur la conscience\u00a0 et la transmission. Je vous l&rsquo;envoie en PDF si vous le souhaitez! Il est \u00e9crit sur le mode oral , je vous mets le premier chapitre!<\/strong><\/p>\n<p><strong>\u00a0 I\/<\/strong><strong>Pourquoi souffrons-nous, \u00e0 quoi servent les \u00e9preuves et les difficult\u00e9s<br \/>\n<\/strong><\/p>\n<p>Nous naissons d\u00e9pendants de nos parents.<\/p>\n<p>Pour acc\u00e9der \u00e0 l\u2019autonomie, nous nous mettons debout apr\u00e8s avoir ramp\u00e9 comme des l\u00e9zards et march\u00e9 \u00e0 quatre pattes comme tous les animaux.<\/p>\n<p>Comment apprenons-nous \u00e0 marcher\u00a0en tant qu\u2019\u00eatre humain?<\/p>\n<p>En imitant les grands, en tombant, en titubant d&rsquo;un c\u00f4t\u00e9 et de l&rsquo;autre, en avant ou en arri\u00e8re, etc. C\u2019est de cette fa\u00e7on que nous appr\u00e9hendons l\u2019espace et c\u2019est \u00e0 force d\u2019essayer et de tomber que nous finissons par trouver l\u2019\u00e9quilibre.<\/p>\n<p>Quand nous passons du tricycle au v\u00e9lo pour la premi\u00e8re fois, l\u00e0 aussi nous cherchons \u00e0 rester en \u00e9quilibre. Si nous ne p\u00e9dalons pas nous tombons. Nous sommes oblig\u00e9s de p\u00e9daler et par l\u00e0 m\u00eame nous trouvons l\u2019\u00e9quilibre dans ce \u00ab\u00a0d\u00e9s\u00e9quilibre\u00a0\u00bb que nous apprenons \u00e0 g\u00e9rer. Pour cela comme pour la marche nous allons devoir faire des exp\u00e9riences r\u00e9p\u00e9t\u00e9es, des apprentissages parfois douloureux.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00ab\u00a0L\u2019art de tenir debout, de maintenir le cap suppose pr\u00e9cis\u00e9ment un horizon plus heureux vers lequel se diriger. Ce qui mine cette progression ce n\u2019est pas la souffrance, ni\u00a0 l\u2019\u00e9chec mais le d\u00e9sespoir. Cesser d\u2019esp\u00e9rer, c\u2019est s\u2019avouer vaincu sans m\u00eame relever le d\u00e9fi, c\u2019est rendre vain chacun de nos efforts\u00a0\u00bb<\/em><\/p>\n<p><em>Alexandre Jollien<\/em><\/p>\n<p>On apprend \u00e0 vivre comme on apprend \u00e0 marcher, \u00e0 parler, \u00e0 faire du v\u00e9lo, en bref \u00e0 trouver notre \u00e9quilibre en permanence. Etc&#8230;<\/p>\n<p>Nous apprenons \u00e0 jongler entre nos d\u00e9sirs, nos besoins, nos \u00e9motions, nos pulsions, notre environnement et ce que les autres peuvent nous apporter ou pas \u2026Pour appr\u00e9hender le monde psychique \u00e9motionnel, nous allons aussi vaciller, tomber, nous tromper avant de trouver un certain \u00e9quilibre. \u00c9quilibre qu\u2019il nous faudra maintenir et r\u00e9ajuster tout au long de notre vie.<\/p>\n<p>Si cet \u00ab\u00a0\u00e9quilibre\u00a0\u00bb repose seulement sur des personnes ou des circonstances ext\u00e9rieures (une situation professionnelle, un statut social, un partenaire) alors, nos chutes risquent de&#8230;<\/p>\n<p><strong>\u00a0Sommaire<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>I\/Pourquoi souffrons-nous? \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: left;\"><strong>II\/ Qu\u2019est-ce que la peur\u00a0?\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: left;\"><strong>III\/ La culpabilit\u00e9\u00a0: un poison mortel.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>IV\/ Les maladies ont-elles un sens\u00a0?\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: left;\"><strong>V\/\u00a0 Le lien entre l\u2019\u00e9nergie et le soleil \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>VI\/\u00a0 De l\u2019importance de bien nourrir tous ses sens.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0VII\/\u00a0 L\u2019enfant et son pouvoir cr\u00e9atif\u00a0: \u00e0 retrouver .\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 <\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0VIII\/\u00a0 Les transmissions\u00a0 dans la famille<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00ab La\u00a0psycho- g\u00e9n\u00e9alogie\u00a0\u00bb \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0IX\/ Pourquoi vivons nous une \u00e9poque formidable\u00a0?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><strong>X\/ <sup>\u00a0<\/sup>D\u00e9couvrir le sens de sa vie.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0XI\/ Pourquoi s\u2019aimer est-il si important\u00a0?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><strong>XII\/\u00a0 Le pouvoir de nos faiblesses<br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0 <img decoding=\"async\" class=\"aligncenter size-medium wp-image-331\" src=\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/PAT-2014-ARGENTINE-287x300.jpg\" alt=\"\" width=\"287\" height=\"300\" srcset=\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/PAT-2014-ARGENTINE-287x300.jpg 287w, https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/PAT-2014-ARGENTINE.jpg 430w\" sizes=\"(max-width: 287px) 100vw, 287px\" \/><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;alchimie de la vie Petit mode d&#8217;emploi pour transformer les \u00e9preuves en cadeaux\u00a0! T\u00e9moignage de Patricia Lagier \u00a0site\u00a0internet Th\u00e9rapeute ma\u00efeutique \u00a0Peinture de Cameron Gray \u00a0 \u00ab\u00a0Dans la beaut\u00e9 j&rsquo;avance. Pr\u00e9c\u00e9d\u00e9 de la beaut\u00e9 j&rsquo;avance. Aur\u00e9ole par la beaut\u00e9 j&rsquo;avance.\u00a0\u00bb Extrait du \u00ab\u00a0 Chant de la nuit\u00a0\u00bb Po\u00e8me navajo \u00ab\u00a0Il est important d\u2019avoir des r\u00eaves assez [&hellip;]<\/p>","protected":false},"author":2,"featured_media":574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;alchimie de la vie Petit mode d&#8217;emploi pour transformer les \u00e9preuves en cadeaux\u00a0! T\u00e9moignage de Patricia Lagier \u00a0site\u00a0internet Th\u00e9rapeute ma\u00efeutique \u00a0Peinture de Cameron Gray \u00a0 \u00ab\u00a0Dans la beaut\u00e9 j&rsquo;avance. Pr\u00e9c\u00e9d\u00e9 de la beaut\u00e9 j&rsquo;avance. Aur\u00e9ole par la beaut\u00e9 j&rsquo;avance.\u00a0\u00bb Extrait du \u00ab\u00a0 Chant de la nuit\u00a0\u00bb Po\u00e8me navajo \u00ab\u00a0Il est important d\u2019avoir des r\u00eaves assez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/architectedevosreves.com\/es\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\" \/>\n<meta property=\"og:site_name\" content=\"Architecte de vos r\u00eaves\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-20T21:37:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T10:38:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"patricia2editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"patricia2editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\"},\"author\":{\"name\":\"patricia2editor\",\"@id\":\"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e\"},\"headline\":\"L&rsquo;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie\",\"datePublished\":\"2018-02-20T21:37:17+00:00\",\"dateModified\":\"2025-11-07T10:38:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\"},\"wordCount\":961,\"image\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg\",\"articleSection\":[\"Connaissance de soi\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\",\"url\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\",\"name\":\"L'alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves\",\"isPartOf\":{\"@id\":\"https:\/\/architectedevosreves.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg\",\"datePublished\":\"2018-02-20T21:37:17+00:00\",\"dateModified\":\"2025-11-07T10:38:25+00:00\",\"author\":{\"@id\":\"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e\"},\"breadcrumb\":{\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage\",\"url\":\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg\",\"contentUrl\":\"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg\",\"width\":240,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/architectedevosreves.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/architectedevosreves.com\/#website\",\"url\":\"https:\/\/architectedevosreves.com\/\",\"name\":\"Architecte de vos r\u00eaves\",\"description\":\"Accompagner les personnes \u00e0 r\u00e9aliser leurs talents\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/architectedevosreves.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e\",\"name\":\"patricia2editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/architectedevosreves.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2cc587883cb01c6a254dcb0d381cd5b98afa8cfde4d59061d84bbf3be5ab079b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2cc587883cb01c6a254dcb0d381cd5b98afa8cfde4d59061d84bbf3be5ab079b?s=96&d=mm&r=g\",\"caption\":\"patricia2editor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"L'alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves","og_description":"L&rsquo;alchimie de la vie Petit mode d&#8217;emploi pour transformer les \u00e9preuves en cadeaux\u00a0! T\u00e9moignage de Patricia Lagier \u00a0site\u00a0internet Th\u00e9rapeute ma\u00efeutique \u00a0Peinture de Cameron Gray \u00a0 \u00ab\u00a0Dans la beaut\u00e9 j&rsquo;avance. Pr\u00e9c\u00e9d\u00e9 de la beaut\u00e9 j&rsquo;avance. Aur\u00e9ole par la beaut\u00e9 j&rsquo;avance.\u00a0\u00bb Extrait du \u00ab\u00a0 Chant de la nuit\u00a0\u00bb Po\u00e8me navajo \u00ab\u00a0Il est important d\u2019avoir des r\u00eaves assez [&hellip;]","og_url":"https:\/\/architectedevosreves.com\/es\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/","og_site_name":"Architecte de vos r\u00eaves","article_published_time":"2018-02-20T21:37:17+00:00","article_modified_time":"2025-11-07T10:38:25+00:00","og_image":[{"width":240,"height":451,"url":"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg","type":"image\/jpeg"}],"author":"patricia2editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"patricia2editor","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#article","isPartOf":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/"},"author":{"name":"patricia2editor","@id":"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e"},"headline":"L&rsquo;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie","datePublished":"2018-02-20T21:37:17+00:00","dateModified":"2025-11-07T10:38:25+00:00","mainEntityOfPage":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/"},"wordCount":961,"image":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage"},"thumbnailUrl":"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg","articleSection":["Connaissance de soi"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/","url":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/","name":"L'alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie &#8902; Architecte de vos r\u00eaves","isPartOf":{"@id":"https:\/\/architectedevosreves.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage"},"image":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage"},"thumbnailUrl":"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg","datePublished":"2018-02-20T21:37:17+00:00","dateModified":"2025-11-07T10:38:25+00:00","author":{"@id":"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e"},"breadcrumb":{"@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#primaryimage","url":"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg","contentUrl":"https:\/\/architectedevosreves.com\/wp-content\/uploads\/2017\/12\/1-e1514665165243.jpg","width":240,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/architectedevosreves.com\/lalchimie-de-vie-petit-livret-ecrit-2011-expliquer-pratique-toute-modestie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/architectedevosreves.com\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;alchimie de la vie un petit livret \u00e9crit en 2011 pour expliquer ce que je pratique en toute modestie"}]},{"@type":"WebSite","@id":"https:\/\/architectedevosreves.com\/#website","url":"https:\/\/architectedevosreves.com\/","name":"Architecte de vos r\u00eaves","description":"Accompagner les personnes \u00e0 r\u00e9aliser leurs talents","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/architectedevosreves.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/architectedevosreves.com\/#\/schema\/person\/6527c41a89cd3ea489521ced59e24f8e","name":"patricia2editor","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/architectedevosreves.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2cc587883cb01c6a254dcb0d381cd5b98afa8cfde4d59061d84bbf3be5ab079b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2cc587883cb01c6a254dcb0d381cd5b98afa8cfde4d59061d84bbf3be5ab079b?s=96&d=mm&r=g","caption":"patricia2editor"}}]}},"_links":{"self":[{"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/posts\/679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/comments?post=679"}],"version-history":[{"count":0,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/posts\/679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/media\/574"}],"wp:attachment":[{"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/media?parent=679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/categories?post=679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/architectedevosreves.com\/es\/wp-json\/wp\/v2\/tags?post=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}